{"id":623,"date":"2013-07-27T16:40:21","date_gmt":"2013-07-27T20:40:21","guid":{"rendered":"http:\/\/medicina.udd.cl\/centro-epidemiologia-politicas-salud\/persona\/claudia-gonzalez-wiedmaier\/"},"modified":"2020-03-27T20:53:29","modified_gmt":"2020-03-27T20:53:29","slug":"claudia-gonzalez-wiedmaier","status":"publish","type":"person","link":"https:\/\/medicina.udd.cl\/icim\/persona\/claudia-gonzalez-wiedmaier\/","title":{"rendered":"Claudia Gonz\u00e1lez"},"featured_media":5193,"template":"","people_tax":[4034,15071,4037,4035],"people_areas":[],"people_levels":[],"class_list":["post-623","person","type-person","status-publish","has-post-thumbnail","hentry","people_tax-autoridad","people_tax-centro-de-epidemiologia-y-politicas-de-salud","people_tax-equipo","people_tax-profesor"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Claudia Gonz\u00e1lez - ICIM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/medicina.udd.cl\/icim\/persona\/claudia-gonzalez-wiedmaier\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Claudia Gonz\u00e1lez - ICIM\" \/>\n<meta property=\"og:url\" content=\"https:\/\/medicina.udd.cl\/icim\/persona\/claudia-gonzalez-wiedmaier\/\" \/>\n<meta property=\"og:site_name\" content=\"ICIM\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-27T20:53:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/medicina.udd.cl\/icim\/files\/2013\/07\/IMG_2273.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"397\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/medicina.udd.cl\/icim\/persona\/claudia-gonzalez-wiedmaier\/\",\"url\":\"https:\/\/medicina.udd.cl\/icim\/persona\/claudia-gonzalez-wiedmaier\/\",\"name\":\"Claudia Gonz\u00e1lez - ICIM\",\"isPartOf\":{\"@id\":\"https:\/\/medicina.udd.cl\/icim\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/medicina.udd.cl\/icim\/persona\/claudia-gonzalez-wiedmaier\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/medicina.udd.cl\/icim\/persona\/claudia-gonzalez-wiedmaier\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/medicina.udd.cl\/icim\/files\/2013\/07\/IMG_2273.jpg\",\"datePublished\":\"2013-07-27T20:40:21+00:00\",\"dateModified\":\"2020-03-27T20:53:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/medicina.udd.cl\/icim\/persona\/claudia-gonzalez-wiedmaier\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/medicina.udd.cl\/icim\/persona\/claudia-gonzalez-wiedmaier\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/medicina.udd.cl\/icim\/persona\/claudia-gonzalez-wiedmaier\/#primaryimage\",\"url\":\"https:\/\/medicina.udd.cl\/icim\/files\/2013\/07\/IMG_2273.jpg\",\"contentUrl\":\"https:\/\/medicina.udd.cl\/icim\/files\/2013\/07\/IMG_2273.jpg\",\"width\":300,\"height\":397},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/medicina.udd.cl\/icim\/persona\/claudia-gonzalez-wiedmaier\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/medicina.udd.cl\/icim\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Personas\",\"item\":\"https:\/\/medicina.udd.cl\/icim\/persona\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Claudia Gonz\u00e1lez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/medicina.udd.cl\/icim\/#website\",\"url\":\"https:\/\/medicina.udd.cl\/icim\/\",\"name\":\"ICIM\",\"description\":\"Una iniciativa de Universidad del Desarrollo y Cl\u00ednica Alemana\",\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Claudia Gonz\u00e1lez - ICIM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/medicina.udd.cl\/icim\/persona\/claudia-gonzalez-wiedmaier\/","og_locale":"es_ES","og_type":"article","og_title":"Claudia Gonz\u00e1lez - ICIM","og_url":"https:\/\/medicina.udd.cl\/icim\/persona\/claudia-gonzalez-wiedmaier\/","og_site_name":"ICIM","article_modified_time":"2020-03-27T20:53:29+00:00","og_image":[{"width":300,"height":397,"url":"https:\/\/medicina.udd.cl\/icim\/files\/2013\/07\/IMG_2273.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/medicina.udd.cl\/icim\/persona\/claudia-gonzalez-wiedmaier\/","url":"https:\/\/medicina.udd.cl\/icim\/persona\/claudia-gonzalez-wiedmaier\/","name":"Claudia Gonz\u00e1lez - ICIM","isPartOf":{"@id":"https:\/\/medicina.udd.cl\/icim\/#website"},"primaryImageOfPage":{"@id":"https:\/\/medicina.udd.cl\/icim\/persona\/claudia-gonzalez-wiedmaier\/#primaryimage"},"image":{"@id":"https:\/\/medicina.udd.cl\/icim\/persona\/claudia-gonzalez-wiedmaier\/#primaryimage"},"thumbnailUrl":"https:\/\/medicina.udd.cl\/icim\/files\/2013\/07\/IMG_2273.jpg","datePublished":"2013-07-27T20:40:21+00:00","dateModified":"2020-03-27T20:53:29+00:00","breadcrumb":{"@id":"https:\/\/medicina.udd.cl\/icim\/persona\/claudia-gonzalez-wiedmaier\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/medicina.udd.cl\/icim\/persona\/claudia-gonzalez-wiedmaier\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/medicina.udd.cl\/icim\/persona\/claudia-gonzalez-wiedmaier\/#primaryimage","url":"https:\/\/medicina.udd.cl\/icim\/files\/2013\/07\/IMG_2273.jpg","contentUrl":"https:\/\/medicina.udd.cl\/icim\/files\/2013\/07\/IMG_2273.jpg","width":300,"height":397},{"@type":"BreadcrumbList","@id":"https:\/\/medicina.udd.cl\/icim\/persona\/claudia-gonzalez-wiedmaier\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/medicina.udd.cl\/icim\/"},{"@type":"ListItem","position":2,"name":"Personas","item":"https:\/\/medicina.udd.cl\/icim\/persona\/"},{"@type":"ListItem","position":3,"name":"Claudia Gonz\u00e1lez"}]},{"@type":"WebSite","@id":"https:\/\/medicina.udd.cl\/icim\/#website","url":"https:\/\/medicina.udd.cl\/icim\/","name":"ICIM","description":"Una iniciativa de Universidad del Desarrollo y Cl\u00ednica Alemana","inLanguage":"es"}]}},"label":"Claudia Gonz\u00e1lez","role":false,"thumbnail_url":"https:\/\/medicina.udd.cl\/icim\/files\/2013\/07\/IMG_2273.jpg","email":"claudiagonzalez@udd.cl","tel_job":"","content":{"rendered":"<div class=\"person-modal person-modal--scl\">\n\t<header class=\"person-modal__header\">\n\t\t<div class=\"person-modal__bg\"><\/div>\n\t\t<div class=\"modal-container\">\n\t\t\t\t\t\t<div class=\"person-modal__media\">\n\t\t\t\t<img width=\"300\" height=\"397\" src=\"https:\/\/medicina.udd.cl\/icim\/files\/2013\/07\/IMG_2273-62x62.jpg\" class=\"person-modal__image wp-post-image lazyload\" alt=\"\" decoding=\"async\" loading=\"lazy\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-src=\"https:\/\/medicina.udd.cl\/icim\/files\/2013\/07\/IMG_2273.jpg\" data-srcset=\"https:\/\/medicina.udd.cl\/icim\/files\/2013\/07\/IMG_2273.jpg 300w, https:\/\/medicina.udd.cl\/icim\/files\/2013\/07\/IMG_2273-227x300.jpg 227w\" \/>\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"person-modal__data\">\n\t\t\t\t<h1 class=\"person-modal__name\">Claudia Gonz\u00e1lez<\/h1>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:&#099;laud&#105;&#097;g&#111;&#110;za&#108;ez&#064;ud&#100;.&#099;l\" class=\"person-modal__email\">c&#108;au&#100;i&#97;&#103;o&#110;&#122;&#97;l&#101;&#122;&#64;&#117;d&#100;&#46;cl<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/header>\n\t<div class=\"modal-container\">\n\t\t\t<div class=\"person-modal__content text\">\n\t\t\t\t\t\t\t\t\t\t<p>Psic\u00f3loga, Universidad Complutense de Madrid. Candidata a Mag\u00edster en Salud P\u00fablica, Universidad de Chile.<\/p>\n<p>Durante 7 a\u00f1os, hasta 1997, se desempe\u00f1\u00f3 en una corporaci\u00f3n de investigaci\u00f3n en epidemiolog\u00eda, realizando entre otros, estudios sobre factores de riesgo para VIH\/SIDA, c\u00e1ncer, prioridades sociales en salud.<\/p>\n<p>En 1997 ingres\u00f3 a trabajar al Departamento de Epidemiolog\u00eda del Ministerio de Salud.<\/p>\n<p>Hasta 2005 se estuvo a cargo de la unidad de estudio del Departamento de Epidemiolog\u00eda, destac\u00e1ndose su participaci\u00f3n en la formulaci\u00f3n del Modelo Nacional de Vigilancia Epidemiol\u00f3gica, los Objetivos Sanitarios para la D\u00e9cada 2000-2010 para Chile, realizaci\u00f3n de encuestas poblacionales para medir calidad de vida, prevalencia de enfermedades y factores riesgo en distintos grupos poblacionales.<\/p>\n<p>Desde 2005 hasta agosto de 2010 coordin\u00f3 el \u00e1rea de epidemiolog\u00eda del Ministerio de Salud de Chile, centr\u00e1ndose sus funciones en el \u00e1mbito de la vigilancia epidemiol\u00f3gica y en el desarrollo de estudios para la toma de decisiones sobre pol\u00edticas p\u00fablicas.<\/p>\n<p>Desde 2002 particip\u00f3 activamente en la elaboraci\u00f3n del Plan Nacional de Enfrentamiento de una Pandemia y en 2009 estuvo a cargo de la secretar\u00eda ejecutiva del Comit\u00e9 de Enfrentamiento de Brotes y Emergencias Sanitarias, entidad responsable del enfrentamiento de la Pandemia 2009 en Chile.\u00a0 Asimismo, fue el punto focal de RSI hasta agosto de 2010 para Chile, y condujo la implementaci\u00f3n de dicho Reglamento en el pa\u00eds.\u00a0 Ha sido miembro de comit\u00e9s de experto para el reglamento Sanitario Internacional en la Organizaci\u00f3n Mundial de la Salud<\/p>\n<p>Actualmente, es docente en el curso de epidemiolog\u00eda y salud p\u00fablica en quinto a\u00f1o de la carrera de medicina, en el Programa de Doctorado en Ciencias e Innovaci\u00f3n en Medicina y en del Diplomado de Epidemiolog\u00eda de Campo.<\/p>\n<p>Ha participado en diversos proyectos de investigaci\u00f3n y consultor\u00edas relacionados con enfermedades infecciosas, prisiones, evaluaci\u00f3n de pol\u00edticas y sistemas de salud.<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n"},"identifier":"17f08933f4b37e058ba32556f07b7415e24dc400","has_credential":[],"given_name":"Claudia","family_name":"Gonz\u00e1lez ","name":"Claudia Gonz\u00e1lez","job_title":"","telephone":"","note":"","im":"","_self_schedule":null,"_links":{"self":[{"href":"https:\/\/medicina.udd.cl\/icim\/wp-json\/wp\/v2\/people\/623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medicina.udd.cl\/icim\/wp-json\/wp\/v2\/people"}],"about":[{"href":"https:\/\/medicina.udd.cl\/icim\/wp-json\/wp\/v2\/types\/person"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medicina.udd.cl\/icim\/wp-json\/wp\/v2\/media\/5193"}],"wp:attachment":[{"href":"https:\/\/medicina.udd.cl\/icim\/wp-json\/wp\/v2\/media?parent=623"}],"wp:term":[{"taxonomy":"people_tax","embeddable":true,"href":"https:\/\/medicina.udd.cl\/icim\/wp-json\/wp\/v2\/people_tax?post=623"},{"taxonomy":"people_areas","embeddable":true,"href":"https:\/\/medicina.udd.cl\/icim\/wp-json\/wp\/v2\/people_areas?post=623"},{"taxonomy":"people_levels","embeddable":true,"href":"https:\/\/medicina.udd.cl\/icim\/wp-json\/wp\/v2\/people_levels?post=623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}