{"id":3986,"date":"2015-12-02T15:59:43","date_gmt":"2015-12-02T18:59:43","guid":{"rendered":"http:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/?p=3986"},"modified":"2016-01-28T13:46:38","modified_gmt":"2016-01-28T16:46:38","slug":"invisten-profesores-titulares-de-la-facultad","status":"publish","type":"post","link":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/noticias\/2015\/12\/02\/invisten-profesores-titulares-de-la-facultad\/","title":{"rendered":"Invisten a profesores titulares de la Facultad"},"content":{"rendered":"<div id=\"gallery-1\" class=\"carousel slide carousel-gallery\" data-ride=\"false\" data-interval=\"false\"><div class=\"carousel-inner\" role=\"listbox\"><figure class=\"carousel-item active\"><img loading=\"lazy\" decoding=\"async\" width=\"529\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-8.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-8.jpg 529w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-8-300x255.jpg 300w\" sizes=\"auto, (max-width: 529px) 100vw, 529px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"685\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-47.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-47.jpg 685w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-47-300x197.jpg 300w\" sizes=\"auto, (max-width: 685px) 100vw, 685px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"601\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-5.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-5.jpg 601w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-5-300x225.jpg 300w\" sizes=\"auto, (max-width: 601px) 100vw, 601px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"644\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-31.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-31.jpg 644w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-31-300x210.jpg 300w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-31-87x62.jpg 87w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-31-365x255.jpg 365w\" sizes=\"auto, (max-width: 644px) 100vw, 644px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-14.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-14.jpg 636w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-14-300x212.jpg 300w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-14-316x224.jpg 316w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-14-87x62.jpg 87w\" sizes=\"auto, (max-width: 636px) 100vw, 636px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"665\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-45.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-45.jpg 665w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-45-300x203.jpg 300w\" sizes=\"auto, (max-width: 665px) 100vw, 665px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"646\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-33.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-33.jpg 646w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-33-300x209.jpg 300w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-33-87x62.jpg 87w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-33-365x255.jpg 365w\" sizes=\"auto, (max-width: 646px) 100vw, 646px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"675\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-18.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-18.jpg 675w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-18-300x200.jpg 300w\" sizes=\"auto, (max-width: 675px) 100vw, 675px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"618\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-1.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-1.jpg 618w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-1-300x218.jpg 300w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-1-87x62.jpg 87w\" sizes=\"auto, (max-width: 618px) 100vw, 618px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"667\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-38.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-38.jpg 667w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-38-300x202.jpg 300w\" sizes=\"auto, (max-width: 667px) 100vw, 667px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"656\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-44.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-44.jpg 656w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-44-300x206.jpg 300w\" sizes=\"auto, (max-width: 656px) 100vw, 656px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"675\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-26.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-26.jpg 675w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-26-300x200.jpg 300w\" sizes=\"auto, (max-width: 675px) 100vw, 675px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"631\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-29.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-29.jpg 631w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-29-300x214.jpg 300w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-29-316x224.jpg 316w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-29-286x205.jpg 286w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-29-87x62.jpg 87w\" sizes=\"auto, (max-width: 631px) 100vw, 631px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"678\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-32.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-32.jpg 678w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-32-300x199.jpg 300w\" sizes=\"auto, (max-width: 678px) 100vw, 678px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"685\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-24.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-24.jpg 685w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-24-300x197.jpg 300w\" sizes=\"auto, (max-width: 685px) 100vw, 685px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"642\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-28.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-28.jpg 642w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-28-300x210.jpg 300w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-28-87x62.jpg 87w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-28-365x255.jpg 365w\" sizes=\"auto, (max-width: 642px) 100vw, 642px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"678\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-30.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-30.jpg 678w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-30-300x199.jpg 300w\" sizes=\"auto, (max-width: 678px) 100vw, 678px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"665\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-21.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-21.jpg 665w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-21-300x203.jpg 300w\" sizes=\"auto, (max-width: 665px) 100vw, 665px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"675\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-9.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-9.jpg 675w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-9-300x200.jpg 300w\" sizes=\"auto, (max-width: 675px) 100vw, 675px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"670\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-27.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-27.jpg 670w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-27-300x201.jpg 300w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"662\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-16.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-16.jpg 662w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-16-300x204.jpg 300w\" sizes=\"auto, (max-width: 662px) 100vw, 662px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"602\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-3.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-3.jpg 602w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-3-300x224.jpg 300w\" sizes=\"auto, (max-width: 602px) 100vw, 602px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"675\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-12.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-12.jpg 675w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-12-300x200.jpg 300w\" sizes=\"auto, (max-width: 675px) 100vw, 675px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"577\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-11.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-11.jpg 577w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-11-300x234.jpg 300w\" sizes=\"auto, (max-width: 577px) 100vw, 577px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"674\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-20.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-20.jpg 674w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-20-300x200.jpg 300w\" sizes=\"auto, (max-width: 674px) 100vw, 674px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"618\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-4.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-4.jpg 618w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-4-300x218.jpg 300w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-4-87x62.jpg 87w\" sizes=\"auto, (max-width: 618px) 100vw, 618px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"662\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-22.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-22.jpg 662w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-22-300x204.jpg 300w\" sizes=\"auto, (max-width: 662px) 100vw, 662px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"487\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-2.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-2.jpg 487w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-2-300x277.jpg 300w\" sizes=\"auto, (max-width: 487px) 100vw, 487px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"689\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-23.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-23.jpg 689w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-23-300x196.jpg 300w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-23-660x430.jpg 660w\" sizes=\"auto, (max-width: 689px) 100vw, 689px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"691\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-48.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-48.jpg 691w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-48-300x195.jpg 300w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-48-660x430.jpg 660w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-48-125x80.jpg 125w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-48-340x220.jpg 340w\" sizes=\"auto, (max-width: 691px) 100vw, 691px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"689\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-43.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-43.jpg 689w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-43-300x196.jpg 300w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-43-660x430.jpg 660w\" sizes=\"auto, (max-width: 689px) 100vw, 689px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-25.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-25.jpg 650w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-25-300x208.jpg 300w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"685\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-34.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-34.jpg 685w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-34-300x197.jpg 300w\" sizes=\"auto, (max-width: 685px) 100vw, 685px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"668\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-37.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-37.jpg 668w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-37-300x202.jpg 300w\" sizes=\"auto, (max-width: 668px) 100vw, 668px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"679\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-36.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-36.jpg 679w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-36-300x199.jpg 300w\" sizes=\"auto, (max-width: 679px) 100vw, 679px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"655\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-41.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-41.jpg 655w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-41-300x206.jpg 300w\" sizes=\"auto, (max-width: 655px) 100vw, 655px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"689\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-50.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-50.jpg 689w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-50-300x196.jpg 300w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-50-660x430.jpg 660w\" sizes=\"auto, (max-width: 689px) 100vw, 689px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"781\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-51.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-51.jpg 781w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-51-300x173.jpg 300w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-51-768x443.jpg 768w\" sizes=\"auto, (max-width: 781px) 100vw, 781px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"652\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-15.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-15.jpg 652w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-15-300x207.jpg 300w\" sizes=\"auto, (max-width: 652px) 100vw, 652px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"634\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-6.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-6.jpg 634w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-6-300x213.jpg 300w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-6-316x224.jpg 316w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-6-87x62.jpg 87w\" sizes=\"auto, (max-width: 634px) 100vw, 634px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-46.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-46.jpg 682w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-46-300x198.jpg 300w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"669\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-40.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-40.jpg 669w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-40-300x202.jpg 300w\" sizes=\"auto, (max-width: 669px) 100vw, 669px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"677\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-39.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-39.jpg 677w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-39-300x199.jpg 300w\" sizes=\"auto, (max-width: 677px) 100vw, 677px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"675\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-17.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-17.jpg 675w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-17-300x200.jpg 300w\" sizes=\"auto, (max-width: 675px) 100vw, 675px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"675\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-13.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-13.jpg 675w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-13-300x200.jpg 300w\" sizes=\"auto, (max-width: 675px) 100vw, 675px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"675\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-7.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-7.jpg 675w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-7-300x200.jpg 300w\" sizes=\"auto, (max-width: 675px) 100vw, 675px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"675\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-49.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-49.jpg 675w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-49-300x200.jpg 300w\" sizes=\"auto, (max-width: 675px) 100vw, 675px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"637\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-35.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-35.jpg 637w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-35-300x212.jpg 300w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-35-316x224.jpg 316w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-35-87x62.jpg 87w\" sizes=\"auto, (max-width: 637px) 100vw, 637px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"675\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-10.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-10.jpg 675w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-10-300x200.jpg 300w\" sizes=\"auto, (max-width: 675px) 100vw, 675px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"685\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-42.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-42.jpg 685w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-42-300x197.jpg 300w\" sizes=\"auto, (max-width: 685px) 100vw, 685px\" \/><\/figure><figure class=\"carousel-item\"><img loading=\"lazy\" decoding=\"async\" width=\"632\" height=\"450\" src=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-19.jpg\" class=\"attachment-landscape_952 size-landscape_952\" alt=\"\" srcset=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-19.jpg 632w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-19-300x214.jpg 300w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-19-316x224.jpg 316w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-19-286x205.jpg 286w, https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-19-87x62.jpg 87w\" sizes=\"auto, (max-width: 632px) 100vw, 632px\" \/><\/figure><\/div><footer class=\"carousel-footer\"><div class=\"carousel-counter\"><span class=\"carousel-counter-current\"><\/span> \/ <span class=\"carousel-counter-total\"><\/span><\/div><a class=\"carousel-control-prev\" href=\"#gallery-1\" role=\"button\" data-slide=\"prev\"><svg aria-hidden=\"true\" class=\"svg-chevron-left-dims\"><use xlink:href='https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/wp-content\/themes\/facultades-2018\/assets\/img\/svg\/dist\/main.svg?version=1695853099#chevron-left'><\/use><\/svg><span class=\"sr-only\">Anterior<\/span><\/a><a class=\"carousel-control-next\" href=\"#gallery-1\" role=\"button\" data-slide=\"next\"><svg aria-hidden=\"true\" class=\"svg-chevron-right-dims\"><use xlink:href='https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/wp-content\/themes\/facultades-2018\/assets\/img\/svg\/dist\/main.svg?version=1695853099#chevron-right'><\/use><\/svg><span class=\"sr-only\">Siguiente<\/span><\/a><\/footer><\/div>\n<p>En un solemne acto realizado en el campus RESB, la Universidad del Desarrollo invisti\u00f3 a 48 docentes de la Facultad de Medicina CAS-UDD, como profesores titulares.<\/p>\n<p style=\"text-align: justify\">Entre los docentes reconocidos destacan profesionales que hacen docencia en distintas carreras de la salud, con destacada trayectoria en Cl\u00ednica Alemana, Hospital Padre Hurtado y en nuestra Facultad.<\/p>\n<p style=\"text-align: justify\">Durante la actividad, el rector de la UDD, Federico Vald\u00e9s, se dirigi\u00f3 a los asistentes recalcando la importancia de esta ceremonia y de la jerarquizaci\u00f3n docente, proceso que se est\u00e1 llevando a cabo en la Universidad desde el a\u00f1o 2012 y en la Facultad de Medicina CAS-UDD desde 2013 y cuyo objetivo es incentivar la carrera de los profesores.<\/p>\n<p style=\"text-align: justify\">La Carrera Acad\u00e9mica es un proceso mediante el cual se reconoce la vinculaci\u00f3n que un acad\u00e9mico tiene con su instituci\u00f3n. Una de sus partes fundamentales es la asignaci\u00f3n de jerarqu\u00edas, instancia que configura la actividad de los docentes e identifica sus m\u00e9ritos, trayectoria y prestigio.<\/p>\n<p style=\"text-align: justify\">\u201cLos criterios de asignaci\u00f3n y ascenso en la escala de jerarqu\u00eda son establecidos a trav\u00e9s de una Comisi\u00f3n de Calificaci\u00f3n Institucional de la UDD, organismo compuesto por personas con una larga trayectoria universitaria y que son reconocidas por sus amplios logros\u201d, indic\u00f3 el vicerrector de postgrado, Sergio Hern\u00e1ndez, durante le ceremonia de investidura.<\/p>\n<p style=\"text-align: justify\">Lista de profesionales investidos:<\/p>\n<ul>\n<li>Renato Acu\u00f1a<\/li>\n<li>Ximena Aguilera<\/li>\n<li>Carmen Paz Astete<\/li>\n<li>Juan Pablo Beca<\/li>\n<li>Ernesto Behnke<\/li>\n<li>Enrique Bosch<\/li>\n<li>B\u00e1ltica Cabieses<\/li>\n<li>Ra\u00fal Cabrera<\/li>\n<li>Claudio Canals<\/li>\n<li>Claudio Carranza<\/li>\n<li>Mario Castro<\/li>\n<li>Felipe Cavagnaro<\/li>\n<li>Julio Cifuentes<\/li>\n<li>Paulette Conget<\/li>\n<li>David Figueroa<\/li>\n<li>Alfredo Gantz<\/li>\n<li>Juan Carlos Glasinovic<\/li>\n<li>Andres Heerlein<\/li>\n<li>Juan Hepp<\/li>\n<li>Arnold Hoppe<\/li>\n<li>Eleonora Horvath<\/li>\n<li>Liliana Jadue<\/li>\n<li>Claus Krebs<\/li>\n<li>Victor Leyton<\/li>\n<li>Luis Miguel Noriega<\/li>\n<li>Enrique Paiva<\/li>\n<li>Francis Palisson<\/li>\n<li>Maria Adriana Parra<\/li>\n<li>Teresa Pelissier<\/li>\n<li>Jorge P\u00e9rez<\/li>\n<li>Julio Pertuiset<\/li>\n<li>Gabriela Repetto<\/li>\n<li>Horacio R\u00edos<\/li>\n<li>Emilio Roessler<\/li>\n<li>Ricardo Ronco<\/li>\n<li>Roque Saenz<\/li>\n<li>Juan Schiller<\/li>\n<li>Pablo Soffia<\/li>\n<li>Luis Thompson<\/li>\n<li>Olivia Trucco<\/li>\n<li>Ivan Urz\u00faa<\/li>\n<li>Ricardo Urz\u00faa<\/li>\n<li>Erick Vald\u00e9s<\/li>\n<li>Renato Verdugo<\/li>\n<li>Fernando Vergara<\/li>\n<li>Pablo Vial<\/li>\n<li>Thomas Weitzel<\/li>\n<li>Patricio Zapata<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el marco de la Carrera Acad\u00e9mica en la Universidad del Desarrollo, 48 docentes de la Facultad de Medicina CAS-UDD fueron reconocidos como profesores titulares. <\/p>\n","protected":false},"author":47,"featured_media":4022,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3986","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Invisten a profesores titulares de la Facultad<\/title>\n<meta name=\"description\" content=\"En un solemne acto realizado en el campus RESB, la Universidad del Desarrollo invisti\u00f3 a 48 docentes de la Facultad de Medicina CAS-UDD, como profesores titulares.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/noticias\/2015\/12\/02\/invisten-profesores-titulares-de-la-facultad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Invisten a profesores titulares de la Facultad\" \/>\n<meta property=\"og:description\" content=\"En un solemne acto realizado en el campus RESB, la Universidad del Desarrollo invisti\u00f3 a 48 docentes de la Facultad de Medicina CAS-UDD, como profesores titulares.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/noticias\/2015\/12\/02\/invisten-profesores-titulares-de-la-facultad\/\" \/>\n<meta property=\"og:site_name\" content=\"Tecnolog\u00eda M\u00e9dica\" \/>\n<meta property=\"article:published_time\" content=\"2015-12-02T18:59:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-01-28T16:46:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-35.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"637\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rominagianotti\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"rominagianotti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/noticias\/2015\/12\/02\/invisten-profesores-titulares-de-la-facultad\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/noticias\/2015\/12\/02\/invisten-profesores-titulares-de-la-facultad\/\"},\"author\":{\"name\":\"rominagianotti\",\"@id\":\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/#\/schema\/person\/d2a1450d36aff8cda548012f30ae8d47\"},\"headline\":\"Invisten a profesores titulares de la Facultad\",\"datePublished\":\"2015-12-02T18:59:43+00:00\",\"dateModified\":\"2016-01-28T16:46:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/noticias\/2015\/12\/02\/invisten-profesores-titulares-de-la-facultad\/\"},\"wordCount\":350,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/noticias\/2015\/12\/02\/invisten-profesores-titulares-de-la-facultad\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-35.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/noticias\/2015\/12\/02\/invisten-profesores-titulares-de-la-facultad\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/noticias\/2015\/12\/02\/invisten-profesores-titulares-de-la-facultad\/\",\"url\":\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/noticias\/2015\/12\/02\/invisten-profesores-titulares-de-la-facultad\/\",\"name\":\"Invisten a profesores titulares de la Facultad\",\"isPartOf\":{\"@id\":\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/noticias\/2015\/12\/02\/invisten-profesores-titulares-de-la-facultad\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/noticias\/2015\/12\/02\/invisten-profesores-titulares-de-la-facultad\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-35.jpg\",\"datePublished\":\"2015-12-02T18:59:43+00:00\",\"dateModified\":\"2016-01-28T16:46:38+00:00\",\"author\":{\"@id\":\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/#\/schema\/person\/d2a1450d36aff8cda548012f30ae8d47\"},\"description\":\"En un solemne acto realizado en el campus RESB, la Universidad del Desarrollo invisti\u00f3 a 48 docentes de la Facultad de Medicina CAS-UDD, como profesores titulares.\",\"breadcrumb\":{\"@id\":\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/noticias\/2015\/12\/02\/invisten-profesores-titulares-de-la-facultad\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/noticias\/2015\/12\/02\/invisten-profesores-titulares-de-la-facultad\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/noticias\/2015\/12\/02\/invisten-profesores-titulares-de-la-facultad\/#primaryimage\",\"url\":\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-35.jpg\",\"contentUrl\":\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-35.jpg\",\"width\":637,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/noticias\/2015\/12\/02\/invisten-profesores-titulares-de-la-facultad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Invisten a profesores titulares de la Facultad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/#website\",\"url\":\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/\",\"name\":\"Tecnolog\u00eda M\u00e9dica\",\"description\":\"Facultad de Medicina Cl\u00ednica Alemana Universidad del Desarrollo\",\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/#\/schema\/person\/d2a1450d36aff8cda548012f30ae8d47\",\"name\":\"rominagianotti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/106dae79925154d9c4e321db25d50a6deb801d5b80ec313022dbea6ef60814cc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/106dae79925154d9c4e321db25d50a6deb801d5b80ec313022dbea6ef60814cc?s=96&d=mm&r=g\",\"caption\":\"rominagianotti\"},\"url\":\"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/noticias\/author\/rominagianotti\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Invisten a profesores titulares de la Facultad","description":"En un solemne acto realizado en el campus RESB, la Universidad del Desarrollo invisti\u00f3 a 48 docentes de la Facultad de Medicina CAS-UDD, como profesores titulares.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/noticias\/2015\/12\/02\/invisten-profesores-titulares-de-la-facultad\/","og_locale":"es_ES","og_type":"article","og_title":"Invisten a profesores titulares de la Facultad","og_description":"En un solemne acto realizado en el campus RESB, la Universidad del Desarrollo invisti\u00f3 a 48 docentes de la Facultad de Medicina CAS-UDD, como profesores titulares.","og_url":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/noticias\/2015\/12\/02\/invisten-profesores-titulares-de-la-facultad\/","og_site_name":"Tecnolog\u00eda M\u00e9dica","article_published_time":"2015-12-02T18:59:43+00:00","article_modified_time":"2016-01-28T16:46:38+00:00","og_image":[{"width":637,"height":450,"url":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-35.jpg","type":"image\/jpeg"}],"author":"rominagianotti","twitter_misc":{"Escrito por":"rominagianotti","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/noticias\/2015\/12\/02\/invisten-profesores-titulares-de-la-facultad\/#article","isPartOf":{"@id":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/noticias\/2015\/12\/02\/invisten-profesores-titulares-de-la-facultad\/"},"author":{"name":"rominagianotti","@id":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/#\/schema\/person\/d2a1450d36aff8cda548012f30ae8d47"},"headline":"Invisten a profesores titulares de la Facultad","datePublished":"2015-12-02T18:59:43+00:00","dateModified":"2016-01-28T16:46:38+00:00","mainEntityOfPage":{"@id":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/noticias\/2015\/12\/02\/invisten-profesores-titulares-de-la-facultad\/"},"wordCount":350,"commentCount":0,"image":{"@id":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/noticias\/2015\/12\/02\/invisten-profesores-titulares-de-la-facultad\/#primaryimage"},"thumbnailUrl":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-35.jpg","articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/noticias\/2015\/12\/02\/invisten-profesores-titulares-de-la-facultad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/noticias\/2015\/12\/02\/invisten-profesores-titulares-de-la-facultad\/","url":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/noticias\/2015\/12\/02\/invisten-profesores-titulares-de-la-facultad\/","name":"Invisten a profesores titulares de la Facultad","isPartOf":{"@id":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/#website"},"primaryImageOfPage":{"@id":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/noticias\/2015\/12\/02\/invisten-profesores-titulares-de-la-facultad\/#primaryimage"},"image":{"@id":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/noticias\/2015\/12\/02\/invisten-profesores-titulares-de-la-facultad\/#primaryimage"},"thumbnailUrl":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-35.jpg","datePublished":"2015-12-02T18:59:43+00:00","dateModified":"2016-01-28T16:46:38+00:00","author":{"@id":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/#\/schema\/person\/d2a1450d36aff8cda548012f30ae8d47"},"description":"En un solemne acto realizado en el campus RESB, la Universidad del Desarrollo invisti\u00f3 a 48 docentes de la Facultad de Medicina CAS-UDD, como profesores titulares.","breadcrumb":{"@id":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/noticias\/2015\/12\/02\/invisten-profesores-titulares-de-la-facultad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/noticias\/2015\/12\/02\/invisten-profesores-titulares-de-la-facultad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/noticias\/2015\/12\/02\/invisten-profesores-titulares-de-la-facultad\/#primaryimage","url":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-35.jpg","contentUrl":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-35.jpg","width":637,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/noticias\/2015\/12\/02\/invisten-profesores-titulares-de-la-facultad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/"},{"@type":"ListItem","position":2,"name":"Invisten a profesores titulares de la Facultad"}]},{"@type":"WebSite","@id":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/#website","url":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/","name":"Tecnolog\u00eda M\u00e9dica","description":"Facultad de Medicina Cl\u00ednica Alemana Universidad del Desarrollo","inLanguage":"es"},{"@type":"Person","@id":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/#\/schema\/person\/d2a1450d36aff8cda548012f30ae8d47","name":"rominagianotti","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/106dae79925154d9c4e321db25d50a6deb801d5b80ec313022dbea6ef60814cc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/106dae79925154d9c4e321db25d50a6deb801d5b80ec313022dbea6ef60814cc?s=96&d=mm&r=g","caption":"rominagianotti"},"url":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/noticias\/author\/rominagianotti\/"}]}},"featured_image_url":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/files\/2015\/12\/Investidura-Profesores-2015-35.jpg","_links":{"self":[{"href":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/wp-json\/wp\/v2\/posts\/3986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/wp-json\/wp\/v2\/users\/47"}],"replies":[{"embeddable":true,"href":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/wp-json\/wp\/v2\/comments?post=3986"}],"version-history":[{"count":6,"href":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/wp-json\/wp\/v2\/posts\/3986\/revisions"}],"predecessor-version":[{"id":4148,"href":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/wp-json\/wp\/v2\/posts\/3986\/revisions\/4148"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/wp-json\/wp\/v2\/media\/4022"}],"wp:attachment":[{"href":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/wp-json\/wp\/v2\/media?parent=3986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/wp-json\/wp\/v2\/categories?post=3986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medicina.udd.cl\/tecnologia-medica-santiago\/wp-json\/wp\/v2\/tags?post=3986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}